{"id":652,"date":"2020-03-10T17:52:23","date_gmt":"2020-03-10T16:52:23","guid":{"rendered":"https:\/\/www.hidalgas.es\/blog\/?p=20058"},"modified":"2020-03-10T17:52:23","modified_gmt":"2020-03-10T16:52:23","slug":"como-purgar-un-radiador","status":"publish","type":"post","link":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador","title":{"rendered":"C\u00f3mo purgar un radiador"},"content":{"rendered":"<p>El radiador es un dispositivo que permite intercambiar calor entre dos medios: uno es el aire del ambiente y el otro es un aparato de climatizaci\u00f3n. Gracias al radiador el aparato no se sobrecalienta. Eventualmente, sea en la casa, el negocio o la oficina, el radiador debe purgarse para garantizar agua caliente y calefacci\u00f3n de calidad, y evitar da\u00f1os en la caldera. Veamos c\u00f3mo purgar un radiador.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-12596 size-large aligncenter\" title=\"pedir presupuesto 2\" src=\"https:\/\/www.hidalgas.es\/blog\/wp-content\/uploads\/pedir-presupuesto-2-700x174.jpg\" alt=\"pedir presupuesto 2\" width=\"700\" height=\"174\" \/><\/p>\n<h2><strong>C\u00f3mo purgar un radiador<\/strong><\/h2>\n<p>Si pones la mano sobre el radiador y est\u00e1 fr\u00edo, significa que es momento de purgarlo. Los puntos fr\u00edos revelan que hay aire atrapado en el interior que ha subido a la parte superior, tomando el lugar del agua caliente que debe estar all\u00ed para calentar el radiador. Afortunadamente dejar salir el aire o purgar el radiador es un proceso bastante simple que se puede lograr tan solo siguiendo algunos pasos.<\/p>\n<h3><strong>Enciende la calefacci\u00f3n central<\/strong><\/h3>\n<p>Enciende la calefacci\u00f3n y sus radiadores. Espera que todos los radiadores se hayan calentado antes de pasar al paso dos.<\/p>\n<h3><strong>Siente todos los radiadores en tu hogar<\/strong><\/h3>\n<p>Toca los radiadores, es importante usar guantes, porque si est\u00e1n funcionando bien te pueden quemar. Las se\u00f1ales reveladoras de que tus radiadores necesitan ser purgados incluyen ruidos de gorgoteo, un radiador que tarda mucho en calentarse o la secci\u00f3n superior se siente significativamente m\u00e1s fr\u00eda en comparaci\u00f3n con la inferior. Debes empezar a purgar los radiadores que est\u00e1n m\u00e1s alejados de la caldera.<\/p>\n<h3><strong>Apaga la calefacci\u00f3n<\/strong><\/h3>\n<p>Mantenga abiertas las v\u00e1lvulas de admisi\u00f3n del radiador, pero mant\u00e9n apagada la calefacci\u00f3n.<\/p>\n<h3><strong>Espera que los radiadores se enfr\u00eden por completo<\/strong><\/h3>\n<p>No intentes purgarlos si a\u00fan est\u00e1n calientes. Tambi\u00e9n es bueno dejar que el contenido de tu radiador se asiente completamente antes de comenzar para una purga m\u00e1s efectiva.<\/p>\n<h3><strong>Toma tus suministros<\/strong><\/h3>\n<p>Algunas cosas que necesitas para purgar un radiador son:<\/p>\n<ul>\n<li>Una llave de radiador<\/li>\n<li>Un pa\u00f1o para sostener<\/li>\n<li>Toallas viejas<\/li>\n<li>Un recipiente para almacenar el goteo<\/li>\n<\/ul>\n<p>Las llaves se suelen suministrar cuando compras el radiador, pero si no es el caso, puedes conseguir una en una tienda de bricolaje.<\/p>\n<h3><strong>Encuentra la v\u00e1lvula de purga<\/strong><\/h3>\n<p>La v\u00e1lvula de purga suele ubicarse en la parte superior del radiador en uno de sus extremos (se ve como un agujero redondo con un cuadrado dentro). Aqu\u00ed se liberar\u00e1 todo el aire y el agua, as\u00ed que coloca tus toallas viejas en el piso debajo de ellas, con el recipiente encima para recoger cualquier derrame.<\/p>\n<h3><strong>Afloja el tornillo de purga<\/strong><\/h3>\n<p>Conecta la llave de radiador en el centro de la v\u00e1lvula de purga y gira el tornillo de purga en sentido antihorario. El pa\u00f1o para sostener te ayudar\u00e1 a ejercer presi\u00f3n y cuando el aire empiece a escapar deber\u00edas escuchar un silbido.<\/p>\n<h3><strong>Espera a que el silbido se detenga por completo<\/strong><\/h3>\n<p>Cuando haya escapado todo el aire la v\u00e1lvula comenzar\u00e1 a gotear. Espera a que aparezca un chorro de agua constante, esta es la se\u00f1al que est\u00e1s buscando de que todo el aire se ha ido.<\/p>\n<h3><strong>Vuelve a apretar la v\u00e1lvula y limpia las gotas<\/strong><\/h3>\n<p>Usa la llave del radiador o un destornillador para apretar el tornillo de purga en el sentido de las agujas del reloj.<\/p>\n<h3><strong>Encienda la calefacci\u00f3n nuevamente<\/strong><\/h3>\n<p>Verifica que el trabajo de purga haya sido exitoso encendiendo la calefacci\u00f3n de nuevo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El radiador es un dispositivo que permite intercambiar calor entre dos medios: uno es el aire del ambiente y el otro es un aparato de climatizaci\u00f3n. Gracias al radiador el aparato no se sobrecalienta. Eventualmente, sea en la casa, el negocio o la oficina, el radiador debe purgarse para garantizar agua caliente y calefacci\u00f3n de&hellip; <a class=\"more-link\" href=\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\">Seguir leyendo <span class=\"screen-reader-text\">C\u00f3mo purgar un radiador<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-652","post","type-post","status-publish","format-standard","hentry","category-calefaccion-y-radiadores","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo purgar un radiador ?\u3010Tenemos la soluci\u00f3n \u3011?<\/title>\n<meta name=\"description\" content=\"En hidalgas te indicamos C\u00f3mo purgar un radiador \u2705 Si no puedes solucionarlo llamanos al Tlf \u27a1\ufe0f \u260e 918 25 80 38 \u260e \u2714\ufe0finfo@hidlagas.es\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo purgar un radiador ?\u3010Tenemos la soluci\u00f3n \u3011?\" \/>\n<meta property=\"og:description\" content=\"En hidalgas te indicamos C\u00f3mo purgar un radiador \u2705 Si no puedes solucionarlo llamanos al Tlf \u27a1\ufe0f \u260e 918 25 80 38 \u260e \u2714\ufe0finfo@hidlagas.es\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\" \/>\n<meta property=\"og:site_name\" content=\"Blog | HidalGas\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T16:52:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hidalgas.es\/blog\/wp-content\/uploads\/pedir-presupuesto-2-700x174.jpg\" \/>\n<meta name=\"author\" content=\"HidalGas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"HidalGas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/\"},\"author\":{\"name\":\"HidalGas\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#\/schema\/person\/eca9e5140abf8c42890a29bfe2a8f412\"},\"headline\":\"C\u00f3mo purgar un radiador\",\"datePublished\":\"2020-03-10T16:52:23+00:00\",\"dateModified\":\"2020-03-10T16:52:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/\"},\"wordCount\":585,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#organization\"},\"articleSection\":[\"Calefacci\u00f3n y radiadores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/\",\"url\":\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/\",\"name\":\"C\u00f3mo purgar un radiador ?\u3010Tenemos la soluci\u00f3n \u3011?\",\"isPartOf\":{\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#website\"},\"datePublished\":\"2020-03-10T16:52:23+00:00\",\"dateModified\":\"2020-03-10T16:52:23+00:00\",\"description\":\"En hidalgas te indicamos C\u00f3mo purgar un radiador \u2705 Si no puedes solucionarlo llamanos al Tlf \u27a1\ufe0f \u260e 918 25 80 38 \u260e \u2714\ufe0finfo@hidlagas.es\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.hidalgas.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo purgar un radiador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#website\",\"url\":\"https:\/\/www.hidalgas.es\/blog\/\",\"name\":\"Blog | HidalGas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hidalgas.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#organization\",\"name\":\"Blog | HidalGas\",\"url\":\"https:\/\/www.hidalgas.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.hidalgas.es\/blog\/wp-content\/uploads\/2023\/06\/hidalgas-logotipo.png\",\"contentUrl\":\"https:\/\/www.hidalgas.es\/blog\/wp-content\/uploads\/2023\/06\/hidalgas-logotipo.png\",\"width\":219,\"height\":36,\"caption\":\"Blog | HidalGas\"},\"image\":{\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#\/schema\/person\/eca9e5140abf8c42890a29bfe2a8f412\",\"name\":\"HidalGas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.hidalgas.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4d998c81597fe67f898e63006ef7f98af4a388418f7a9b8c3804bd9a884b9de2?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4d998c81597fe67f898e63006ef7f98af4a388418f7a9b8c3804bd9a884b9de2?s=96&d=blank&r=g\",\"caption\":\"HidalGas\"},\"url\":\"https:\/\/www.hidalgas.es\/blog\/author\/hidalgas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo purgar un radiador ?\u3010Tenemos la soluci\u00f3n \u3011?","description":"En hidalgas te indicamos C\u00f3mo purgar un radiador \u2705 Si no puedes solucionarlo llamanos al Tlf \u27a1\ufe0f \u260e 918 25 80 38 \u260e \u2714\ufe0finfo@hidlagas.es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo purgar un radiador ?\u3010Tenemos la soluci\u00f3n \u3011?","og_description":"En hidalgas te indicamos C\u00f3mo purgar un radiador \u2705 Si no puedes solucionarlo llamanos al Tlf \u27a1\ufe0f \u260e 918 25 80 38 \u260e \u2714\ufe0finfo@hidlagas.es","og_url":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador","og_site_name":"Blog | HidalGas","article_published_time":"2020-03-10T16:52:23+00:00","og_image":[{"url":"https:\/\/www.hidalgas.es\/blog\/wp-content\/uploads\/pedir-presupuesto-2-700x174.jpg"}],"author":"HidalGas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"HidalGas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/#article","isPartOf":{"@id":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/"},"author":{"name":"HidalGas","@id":"https:\/\/www.hidalgas.es\/blog\/#\/schema\/person\/eca9e5140abf8c42890a29bfe2a8f412"},"headline":"C\u00f3mo purgar un radiador","datePublished":"2020-03-10T16:52:23+00:00","dateModified":"2020-03-10T16:52:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/"},"wordCount":585,"commentCount":0,"publisher":{"@id":"https:\/\/www.hidalgas.es\/blog\/#organization"},"articleSection":["Calefacci\u00f3n y radiadores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/","url":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/","name":"C\u00f3mo purgar un radiador ?\u3010Tenemos la soluci\u00f3n \u3011?","isPartOf":{"@id":"https:\/\/www.hidalgas.es\/blog\/#website"},"datePublished":"2020-03-10T16:52:23+00:00","dateModified":"2020-03-10T16:52:23+00:00","description":"En hidalgas te indicamos C\u00f3mo purgar un radiador \u2705 Si no puedes solucionarlo llamanos al Tlf \u27a1\ufe0f \u260e 918 25 80 38 \u260e \u2714\ufe0finfo@hidlagas.es","breadcrumb":{"@id":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hidalgas.es\/blog\/como-purgar-un-radiador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hidalgas.es\/blog\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo purgar un radiador"}]},{"@type":"WebSite","@id":"https:\/\/www.hidalgas.es\/blog\/#website","url":"https:\/\/www.hidalgas.es\/blog\/","name":"Blog | HidalGas","description":"","publisher":{"@id":"https:\/\/www.hidalgas.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hidalgas.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hidalgas.es\/blog\/#organization","name":"Blog | HidalGas","url":"https:\/\/www.hidalgas.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hidalgas.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.hidalgas.es\/blog\/wp-content\/uploads\/2023\/06\/hidalgas-logotipo.png","contentUrl":"https:\/\/www.hidalgas.es\/blog\/wp-content\/uploads\/2023\/06\/hidalgas-logotipo.png","width":219,"height":36,"caption":"Blog | HidalGas"},"image":{"@id":"https:\/\/www.hidalgas.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hidalgas.es\/blog\/#\/schema\/person\/eca9e5140abf8c42890a29bfe2a8f412","name":"HidalGas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hidalgas.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4d998c81597fe67f898e63006ef7f98af4a388418f7a9b8c3804bd9a884b9de2?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d998c81597fe67f898e63006ef7f98af4a388418f7a9b8c3804bd9a884b9de2?s=96&d=blank&r=g","caption":"HidalGas"},"url":"https:\/\/www.hidalgas.es\/blog\/author\/hidalgas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/posts\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/comments?post=652"}],"version-history":[{"count":0,"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/posts\/652\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/media?parent=652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/categories?post=652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hidalgas.es\/blog\/wp-json\/wp\/v2\/tags?post=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}